{"id":6981,"date":"2020-08-26T18:31:31","date_gmt":"2020-08-26T22:31:31","guid":{"rendered":"https:\/\/ecom.o-possum.com\/vertige-escalade\/?page_id=6981"},"modified":"2023-10-31T13:20:06","modified_gmt":"2023-10-31T17:20:06","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/ecom.o-possum.com\/vertige-escalade\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6981\" class=\"elementor elementor-6981\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-497523a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"497523a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fbf6ec3\" data-id=\"fbf6ec3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f55619 elementor-widget elementor-widget-heading\" data-id=\"7f55619\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-757ec9e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"757ec9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><span data-contrast=\"auto\">Introduction<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><\/ol><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Le respect de votre confidentialit\u00e9 est un enjeu au c\u0153ur des pr\u00e9occupations de l&#8217;\u00e9quipe O-Possum. Nous nous engageons donc \u00e0 respecter la confidentialit\u00e9 des Renseignements personnels en se conformant \u00e0 la <\/span><i><span data-contrast=\"auto\">Politique de confidentialit\u00e9 <\/span><\/i><span data-contrast=\"auto\">(ci-apr\u00e8s <\/span><span data-contrast=\"auto\">\u00ab<\/span><span data-contrast=\"auto\"> Politique<\/span><span data-contrast=\"auto\"> \u00bb<\/span><span data-contrast=\"auto\">) suivante. <\/span><span data-contrast=\"auto\">La pr\u00e9sente Politique s\u2019applique \u00e0 tous les sites web transactionnel d\u00e9butant par https:\/\/ecom.o-possum[&#8230;].<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Cette Politique lie tous les utilisateur de l\u2019un de sites mentionn\u00e9s ci-dessus (ci-apr\u00e8s <\/span><span data-contrast=\"auto\">\u00ab<\/span><span data-contrast=\"auto\"> vous <\/span><span data-contrast=\"auto\">\u00bb<\/span><span data-contrast=\"auto\">)) et l\u2019\u00e9quipe de Solutions O-Possum aussi immatricul\u00e9 sous le nom 9413-8856 Qu\u00e9bec inc. (ci-apr\u00e8s <\/span><span data-contrast=\"auto\">\u00ab<\/span><span data-contrast=\"auto\"> nous<\/span><span data-contrast=\"auto\"> \u00bb<\/span><span data-contrast=\"auto\"> ou <\/span><span data-contrast=\"auto\">\u00ab<\/span><span data-contrast=\"auto\"> O-Possum<\/span><span data-contrast=\"auto\">\u00bb<\/span><span data-contrast=\"auto\">).\u00a0\u00a0 Elle ne lie pas toutes autres entreprises qui ne sont pas poss\u00e9d\u00e9es ou contr\u00f4l\u00e9es ni toutes personnes qui ne sont pas employ\u00e9s d\u2019O-Possum. Cette Politique lie \u00e9galement toutes personnes morales dont le repr\u00e9sentant est l\u00e9galement autoris\u00e9 \u00e0 lier cette derni\u00e8re \u00e0 la pr\u00e9sente Politique.\u00a0 Si vous n&#8217;avez pas l&#8217;autorit\u00e9 pour lier la personne morale que vous repr\u00e9sentez ou si vous ne consentez pas aux termes et conditions pr\u00e9vus aux pr\u00e9sentes, il est de votre responsabilit\u00e9 de ne pas naviguer sur site web ni d&#8217;utiliser tout autre produit ou service offerts par O-Possum qui requi\u00e8re la collecte de renseignements personnels.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Cette Politique d\u00e9crit les types de renseignement personnel que nous pouvons collecter ou que vous pouvez volontairement nous fournir par l\u2019entremise du site web d\u2019O-Possum ou de tout autre site ou plateforme affili\u00e9s \u00e0 O-Possum permettant de g\u00e9rer les activit\u00e9s commerciales qui n\u00e9cessitent une interaction avec vous.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:276}\"> <br \/><\/span><\/p><p><span data-contrast=\"auto\">2. Terminologie<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">\u00ab<\/span><b><span data-contrast=\"auto\"> Plateforme <\/span><\/b><span data-contrast=\"auto\">\u00bb<\/span><span data-contrast=\"auto\"> d\u00e9signe, en plus du pr\u00e9sent site web, tout autre site, logiciel ou technologie acessible aux utilisateurs par O-Possum ou sa soci\u00e9t\u00e9 affili\u00e9e Solutions O-Possum.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">\u00ab<\/span><b><span data-contrast=\"auto\"> T\u00e9moins de connexion<\/span><\/b><span data-contrast=\"auto\"> \u00bb<\/span><span data-contrast=\"auto\"> d\u00e9signe de l\u2019information \u00e9chang\u00e9e entre un navigateur et un serveur internet lorsqu\u2019un utilisateur visite un site web.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">\u00ab<\/span><b><span data-contrast=\"auto\"> Renseignements personnels<\/span><\/b><span data-contrast=\"auto\"> \u00bb<\/span><span data-contrast=\"auto\"> signifie <\/span><span data-contrast=\"auto\">\u00ab<\/span><span data-contrast=\"auto\"> tout renseignement qui concerne une personne physique et permet de l\u2019identifier<\/span><span data-contrast=\"auto\"> \u00bb<\/span><span data-contrast=\"auto\"> (art. 2 de la Loi sur la protection des renseignements personnels dans le secteur priv\u00e9) ;<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">\u00ab<\/span><b><span data-contrast=\"auto\"> Renseignements personnels sensibles <\/span><\/b><span data-contrast=\"auto\">\u00bb<\/span><span data-contrast=\"auto\"> est d\u00e9fini comme un renseignement qui, de par <\/span><span data-contrast=\"auto\">\u00ab<\/span><span data-contrast=\"auto\"> sa nature notamment m\u00e9dicale, biom\u00e9trique ou autrement intime ou en raison du contexte de son utilisation ou de sa communication, [&#8230;] suscite un haut degr\u00e9 d\u2019attente raisonnable en mati\u00e8re de vie priv\u00e9e <\/span><span data-contrast=\"auto\">\u00bb<\/span><span data-contrast=\"auto\"> selon la Commission d&#8217;acc\u00e8s \u00e0 l&#8217;information du Qu\u00e9bec (<\/span><a href=\"https:\/\/www.cai.gouv.qc.ca\/espace-evolutif-modernisation-lois\/thematiques\/renseignements-sensibles\/\"><span data-contrast=\"auto\">https:\/\/www.cai.gouv.qc.ca\/espace-evolutif-modernisation-lois\/thematiques\/renseignements-sensibles\/<\/span><\/a><span data-contrast=\"auto\"> );<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">3. Param\u00e8tre de confidentialit\u00e9 par d\u00e9faut<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Tel que requis par la loi, en tant qu&#8217;organisation nous nous engageons \u00e0 assurer, par d\u00e9faut, le plus haut niveau de confidentialit\u00e9 \u00e0 toute \u00e9tape du cycle de vie des renseignements personnels de nos utilisateurs, et ce, sans aucune intervention de votre part.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0Il est \u00e0 noter que cette clause ne s&#8217;applique pas aux param\u00e8tres de confidentialit\u00e9 des t\u00e9moins de connexion aussi connus sous le nom <\/span><i><span data-contrast=\"auto\">Cookies. <\/span><\/i><span data-contrast=\"auto\">Pour plus d\u2019information sur les param\u00e8tres relatifs aux <\/span><i><span data-contrast=\"auto\">Cookies<\/span><\/i><span data-contrast=\"auto\"> veuillez vous r\u00e9f\u00e9rer \u00e0 la <\/span><i><span data-contrast=\"auto\">Section 11: T\u00e9moins de connexion<\/span><\/i><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">4. Consentement<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Le consentement des utilisateurs aux diff\u00e9rentes \u00e9tapes du cycle de vie des renseignements personnels doit \u00eatre manifeste, libre, \u00e9clair\u00e9 et donn\u00e9 \u00e0 des fins sp\u00e9cifiques. Le consentement d\u2019un utilisateur sera requis sauf dans les situations exceptionnelles pr\u00e9vues par la loi.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Nous nous engageons \u00e0 utiliser les renseignements personnels d&#8217;un utilisateur uniquement aux fins pour lesquelles ils ont \u00e9t\u00e9 demand\u00e9s et pour lesquelles un utilisateur a consenti \u00e0 les fournir (voir <\/span><i><span data-contrast=\"auto\">Section 6: Utilisation des renseignements collect\u00e9s<\/span><\/i><span data-contrast=\"auto\">) . <\/span><span data-contrast=\"auto\">Dans l&#8217;\u00e9ventualit\u00e9 o\u00f9 nous aurions besoin d&#8217;utiliser les renseignements personnels d&#8217;un utilisateur \u00e0 d&#8217;autres fins que celles pour lesquelles il avait initialement donn\u00e9 son consentement, nous nous engageons \u00e0 obtenir son consentement \u00e0 nouveau.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Pour tous renseignements personnels non sensibles, tout utilisateur devra donner un consentement implicite, soit en fournissant de mani\u00e8re volontaire les renseignements demand\u00e9s.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Pour tous Renseignements personnels sensibles, chaque utilisateur devra nous fournir un consentement expr\u00e8s, soit en cochant la case \u00e0 cet effet dans le formulaire demandant ce type de renseignement, sans quoi nous ne serons pas autoris\u00e9s \u00e0 utiliser ces renseignements.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">En naviguant sur le site web ou en utilisant tout autre produit et service offert par O-Possum, l\u2019utilisateur reconna\u00eet avoir lu et compris la pr\u00e9sente Politique et est r\u00e9put\u00e9 avoir accept\u00e9 d&#8217;\u00eatre li\u00e9 par les termes et conditions de cette derni\u00e8re.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p aria-level=\"3\"><span data-contrast=\"auto\">Utilisateurs mineurs<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559731&quot;:0,&quot;335559738&quot;:320,&quot;335559739&quot;:80,&quot;335559740&quot;:276,&quot;335559991&quot;:360}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Nous refusons de collecter tout renseignement personnel fournit par un enfant de moins de dix-huit (18) ans sans le consentement du titulaire de l&#8217;autorit\u00e9 parentale ou du tuteur l\u00e9gal. Si vous \u00eates un utilisateur de moins de dix-huit (18) ans, nous vous prions de ne pas soumettre de renseignements personnels \u00e0 votre sujet par l&#8217;entremise de notre site web ou de tout autre Produit et Service offert par O-Possum.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Si vous avez des raisons de croire qu&#8217;un enfant de moins de dix-huit (18) ans nous a fourni des renseignements personnels sans le consentement du titulaire de l&#8217;autorit\u00e9 parentale ou du tuteur l\u00e9gal, veuillez nous en aviser d\u00e8s que possible afin que nous puissions proc\u00e9der \u00e0 la destruction des renseignements personnels concernant l&#8217;enfant en question (voir <\/span><i><span data-contrast=\"auto\">Section 17: Responsable de protection des renseignements personnels<\/span><\/i><span data-contrast=\"auto\">)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Nous encourageons fortement les titulaires de l&#8217;autorit\u00e9 parentale et les tuteurs l\u00e9gaux \u00e0 sensibiliser leurs enfants \u00e0 ne pas fournir de renseignements personnels \u00e0 toute organisation, que ce soit en succursale ou par l&#8217;entremise d&#8217;un site web, sans leur permission et \u00e0 prendre toutes les pr\u00e9cautions n\u00e9cessaires \u00e0 ce sujet.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">5. Collecte de renseignements personnels<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Il est possible de naviguer sur notre site web ou d&#8217;utiliser certains produits et services offerts par O-Possum sans avoir \u00e0 divulguer quelconque information permettant de vous identifier en tant qu&#8217;individu sp\u00e9cifique.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Cependant, certaines fonctionnalit\u00e9s de notre Site web et certaines transactions sur place requiert de fournir des renseignements personnels afin d&#8217;avoir acc\u00e8s \u00e0 un produit ou un service. Ainsi, les utilisateurs choisissent de fournir volontairement des renseignements personnels afin d&#8217;avoir acc\u00e8s aux produits et services en question.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">L\u2019utilisateur peut choisir de ne pas fournir les renseignements personnels demand\u00e9s. Toutefois, il est possible qu&#8217;il ne puisse pas avoir acc\u00e8s \u00e0 certains produits ou services. Pour toutes questions relatives aux renseignements qui doivent obligatoirement \u00eatre fournis, nous vous invitons \u00e0 nous contacter afin que nous puissions vous \u00e9clair (voir <\/span><i><span data-contrast=\"auto\">Section 17 : Responsable de la protection des renseignements personnels.<\/span><\/i><span data-contrast=\"auto\">)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">6. Utilisation des renseignements collect\u00e9s<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">L\u2019utilisation est la p\u00e9riode durant laquelle une personne autoris\u00e9e par O-Possum, utilise un renseignement confidentiel pour les fins auxquelles un utilisateur a consenti de fournir ces renseignements.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">\u00c0 l&#8217;\u00e9tape de l&#8217;utilisation des renseignements, nous nous engageons \u00e0 ce que les acc\u00e8s aux renseignements personnels soient uniquement donn\u00e9s aux personnes ayant la qualit\u00e9 pour recevoir ce type d&#8217;information n\u00e9cessaire \u00e0 l&#8217;exercice de ses fonctions. De plus, nous nous engageons \u00e0 obtenir le consentement d&#8217;un utilisateur si nous avons besoin d&#8217;utiliser des renseignements confidentiels pour une autre fin que celles pour lesquelles il avait initialement donn\u00e9 son consentement sous r\u00e9serves des exceptions pr\u00e9vues par loi.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Selon le type de produit et service d\u00e9sir\u00e9 un utilisateur, les renseignements personnels collect\u00e9s peuvent notamment \u00eatre utilis\u00e9s aux fins suivantes :<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><ul><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Gestion de compte utilisateur<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">S\u00e9curit\u00e9<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Paiements<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Livrer des produits ou des services<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">Envoyer de l&#8217;informations administrative<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">Envoyer des communications marketing et promotionnelles<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Envoyer des mises \u00e0 jour de produits et de services<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">R\u00e9pondre aux demandes de renseignements et offrir un soutien<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Diffusez des publicit\u00e9s cibl\u00e9es<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">Produire des Relev\u00e9 24<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">Analyse de donn\u00e9es pour le marketing et la publicit\u00e9<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">7. Traitement des paiements<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Lorsqu&#8217;un utilisateur doit effectuer un paiement, il devra in\u00e9vitablement fournir les d\u00e9tails de sa carte de cr\u00e9dit ou les renseignements n\u00e9cessaires pour tout autre mode de paiement. Ces donn\u00e9es seront uniquement utilis\u00e9es dans le but d&#8217;effectuer la transaction pour laquelle elles ont \u00e9t\u00e9 fournies. Nous utilisons des interm\u00e9diaires, soit des processeurs de paiement, pour effectuer le traitement des donn\u00e9es relatives aux paiements de mani\u00e8re s\u00e9curitaire. Les renseignements vis\u00e9s par la pr\u00e9sente section sont notamment les suivants: une adresse courriel, une adresse \u00e0 domicile, les d\u00e9tails d&#8217;une carte de cr\u00e9dit et\/ou le num\u00e9ro de compte de banque pour leur permettre de compl\u00e9ter les transactions d\u00e9sir\u00e9es.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Les renseignements personnels n\u00e9cessaires au traitement d&#8217;un paiement futur ou de paiements r\u00e9currents seront stock\u00e9s sous forme crypt\u00e9e sur les serveurs s\u00e9curis\u00e9s de nos processeurs de paiement si un consentement pr\u00e9alable de l\u2019utilisateur a \u00e9t\u00e9 donn\u00e9 \u00e0 cet effet.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">8. Droit d&#8217;acc\u00e8s et de modification<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Un utilisateur peut faire une demande au Responsable de la protection des renseignements personnels afin de faire supprimer ou modifier certains renseignements personnels le concernant qui sont enregistr\u00e9s dans nos bases de donn\u00e9es. Pour ce faire, l\u2019utilisateur devra envoyer un courriel au responsable dont l&#8217;objet est le suivant : <\/span><i><span data-contrast=\"auto\">Acc\u00e8s ou modifications de mes renseignements personnels.<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Tel que requis par la loi, le Responsable de la protection des renseignements personnels donnera suite \u00e0 toute demande d&#8217;acc\u00e8s ou de rectifications de la part d&#8217;un utilisateur dans les 30 jours de la r\u00e9ception de la demande.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Il est \u00e0 noter que lorsqu&#8217;un renseignement est effac\u00e9 ou modifi\u00e9, nous conservons une copie des renseignements personnels pr\u00e9sents avant la modification ou la suppression dans nos dossiers pendant la dur\u00e9e n\u00e9cessaire pour nous conformer \u00e0 nos obligations l\u00e9gales et fiscales.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p aria-level=\"3\"><span data-contrast=\"auto\">Transparence<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:1440,&quot;335559738&quot;:320,&quot;335559739&quot;:80,&quot;335559740&quot;:276,&quot;335559991&quot;:360}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Par souci de transparence et sur demande d&#8217;un utilisateur, nous nous engageons \u00e9galement \u00e0 fournir les informations suivantes :<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><ul><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Les renseignements personnels que nous avons \u00e0 son sujet ;<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Une liste des cat\u00e9gories de personnes qui ont acc\u00e8s \u00e0 aux renseignements \u00e0 son sujet au sein de l\u2019entreprise<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">La dur\u00e9e pour laquelle nous conservons les renseignements en question ;<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\u25cf\" data-font=\"lexend\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\u25cf&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Les coordonn\u00e9es du responsable de la protection des renseignements personnels.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Ces informations seront transmises \u00e0 l\u2019utilisateur dans un format technologique structur\u00e9 et couramment utilis\u00e9, \u00e0 la demande de ce dernier, tel que requis par la loi.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">9. Communication des renseignements personnels<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p aria-level=\"3\"><span data-contrast=\"auto\">Fournisseurs de service<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:1440,&quot;335559738&quot;:320,&quot;335559739&quot;:80,&quot;335559740&quot;:276,&quot;335559991&quot;:360}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Selon la nature de la transaction qu&#8217;un utilisateur d\u00e9sire effectuer, il est possible que nous soyons dans l&#8217;obligation de partager des renseignements personnels avec des fournisseurs de services qui sont essentiels pour assurer le bon fonctionnement du site web ou de certains produits et services offerts chez O-Possum Nous vous assurons que les politiques de confidentialit\u00e9 de tous nos fournisseurs de service sont conformes aux n\u00f4tres ou que ces derniers acceptent de respecter notre Politique afin d&#8217;assurer la protection des renseignements personnels de nos utilisateurs.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Les fournisseurs de service ne sont pas autoris\u00e9s \u00e0 utiliser ou divulguer vos renseignements personnels \u00e0 l&#8217;exception des renseignements n\u00e9cessaires pour effectuer les services requis en notre nom ou pour respecter des normes l\u00e9gales. Ainsi, nous divulguons uniquement les renseignements n\u00e9cessaires pour qu\u2019ils puissent remplir leurs fonctions. Enfin, ces fournisseurs ne sont pas autoris\u00e9s \u00e0 utiliser ou divulguer toute information que nous leur avons fournie pour leur propre marketing ou b\u00e9n\u00e9fice.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p aria-level=\"3\"><span data-contrast=\"auto\">Tiers<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:1440,&quot;335559738&quot;:320,&quot;335559739&quot;:80,&quot;335559740&quot;:276,&quot;335559991&quot;:360}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Nous ne partageons aucun renseignement confidentiel avec des tiers. Toutefois, nous pouvons divulguer tout renseignement personnel que nous recueillons, utilisons ou recevons si la loi l&#8217;exige ou l&#8217;autorise.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">10. Conservation des renseignements personnels<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Nous conserverons et utiliserons vos renseignements personnels durant toute p\u00e9riode n\u00e9cessaire pour offrir le produit ou service \u00e0 la demande d&#8217;un utilisateur, pour nous conformer \u00e0 nos obligations l\u00e9gales, pour faire respecter nos accords ou pour r\u00e9soudre les litiges \u00e0 moins qu&#8217;une p\u00e9riode de conservation plus longue ne soit requise ou autoris\u00e9e par la loi.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00a0<\/span><span data-contrast=\"auto\">Une fois la p\u00e9riode de conservation expir\u00e9e, les renseignements personnels seront supprim\u00e9s. Par cons\u00e9quent, le droit d&#8217;acc\u00e8s, le droit d&#8217;effacer, le droit de modifier et le droit \u00e0 la portabilit\u00e9 des donn\u00e9es ne pourront pas \u00eatre exerc\u00e9s apr\u00e8s l&#8217;expiration de la p\u00e9riode de conservation.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p aria-level=\"3\"><span data-contrast=\"auto\">Destruction des renseignements personnels<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559731&quot;:0,&quot;335559738&quot;:320,&quot;335559739&quot;:80,&quot;335559740&quot;:276,&quot;335559991&quot;:360}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">La destruction des renseignements personnels se d\u00e9roule \u00e0 la fin de leur cycle de vie, soit lorsque la finalit\u00e9 pour laquelle l&#8217;information a \u00e9t\u00e9 collect\u00e9e est accomplie ou selon ce qui est pr\u00e9vu par la loi. \u00c0 cette \u00e9tape, nous d\u00e9truirons les renseignements personnels s\u00e9curitairement.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">11. T\u00e9moins de connexion (<\/span><i><span data-contrast=\"auto\">Cookie<\/span><\/i><span data-contrast=\"auto\">)<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Notre site web peut utiliser des outils d&#8217;analyse tiers qui d\u00e9posent diff\u00e9rent t\u00e9moins de connexion ou d&#8217;autres technologies similaires pour collecter des informations standard sur l&#8217;activit\u00e9 et l&#8217;utilisation d&#8217;Internet. Les t\u00e9moins de connexions permettent aux utilisateurs d\u2019optimiser leur navigation sur le site web et am\u00e9liore leur exp\u00e9rience client chez O-Possum.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Les principaux t\u00e9moins de connexion utilis\u00e9s sont:<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"19\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Google Analytics<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"19\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Google Tag Manager<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"19\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Facebook Pixel<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Voici une description des cat\u00e9gories de t\u00e9moins de connexion utilis\u00e9s.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p aria-level=\"3\"><span data-contrast=\"auto\">T\u00e9moins n\u00e9cessaires<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:1440,&quot;335559738&quot;:320,&quot;335559739&quot;:80,&quot;335559740&quot;:276,&quot;335559991&quot;:360}\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Il s\u2019agit de t\u00e9moins de connexions n\u00e9cessaires pour naviguer et utiliser les fonctionnalit\u00e9s de base de notre site web. Ce type de t\u00e9moins est activ\u00e9 par d\u00e9faut sans quoi vous ne pourrez pas acc\u00e9der au site web.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p aria-level=\"3\"><span data-contrast=\"auto\">T\u00e9moins de performance<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:1440,&quot;335559738&quot;:320,&quot;335559739&quot;:80,&quot;335559740&quot;:276,&quot;335559991&quot;:360}\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00c0 l\u2019aide des t\u00e9moins de performance, les informations recueillies sont utilis\u00e9es pour compiler des rapports statistiques sur l&#8217;activit\u00e9 des utilisateurs, tels que la fr\u00e9quence \u00e0 laquelle les utilisateurs visitent notre site web, les pages qu&#8217;ils visitent, pendant combien de temps, le type de navigateur utilis\u00e9, etc. Nous utilisons les informations obtenues \u00e0 partir de ces outils d&#8217;analyse pour surveiller les performances et am\u00e9liorer notre site web et nos produits et services. Ces t\u00e9moins ne sont pas activ\u00e9s par d\u00e9faut.<\/span><\/p><p aria-level=\"3\"><span data-contrast=\"auto\">T\u00e9moins de publicit\u00e9 cibl\u00e9\u00a0<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:1440,&quot;335559738&quot;:320,&quot;335559739&quot;:80,&quot;335559740&quot;:276,&quot;335559991&quot;:360}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0Les t\u00e9moins de publicit\u00e9 cibli\u00e9 recuille des informations qui permettent notamment de personnaliser les publicit\u00e9s, d\u2019\u00e9valuer l\u2019efficacit\u00e9 d\u2019une campagne publicitaire et d\u2019am\u00e9liorer les produits et services offert par O-Possum. Ces t\u00e9moins ne sont pas activ\u00e9s par d\u00e9faut.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0Il est \u00e0 noter que nous n\u2019utilisons pas des outils d&#8217;analyse tiers pour suivre ou collecter des renseignements personnels qui permettent d&#8217;identifier les utilisateurs. De plus, nous n&#8217;associons aucun renseignement recueilli \u00e0 partir des rapports statistiques \u00e0 un utilisateur pr\u00e9cis.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p aria-level=\"3\"><span data-contrast=\"auto\">Modification des pr\u00e9f\u00e9rences<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:1440,&quot;335559738&quot;:320,&quot;335559739&quot;:80,&quot;335559740&quot;:276,&quot;335559991&quot;:360}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">La majorit\u00e9 des site web utilise des t\u00e9moins de connexion et il n&#8217;est pas dangereux de partager des informations sur le site web d\u2019une entreprise en qui vous avez confiance. Sachez que vous avez le contr\u00f4le sur les informations qui sont partag\u00e9 sur le site web et que vous avez la possibilit\u00e9 de modifier vos pr\u00e9f\u00e9rences \u00e0 tout moment.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Voici deux options vous permettant de modifier vos pr\u00e9f\u00e9rences quant aux t\u00e9moins de connexion:<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><ul><li data-leveltext=\"%1)\" data-font=\"lexend\" data-listid=\"17\" data-list-defn-props=\"{&quot;335552541&quot;:0,&quot;335559684&quot;:-1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[65533,4],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;%1)&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Bande s\u2019affichant au bas de l\u2019\u00e9cran, sur le site web<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span data-contrast=\"auto\">R\u00e9glages de votre appareil ou de votre navigateur \u2013 Veuillez vous r\u00e9f\u00e9rez aux indications de votre appareil ou navigateur \u00e0 ce sujet.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><\/ul><p><span data-contrast=\"auto\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">12. Publicit\u00e9<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Nous pouvons autoriser certaines soci\u00e9t\u00e9s tierces \u00e0 nous aider \u00e0 personnaliser la publicit\u00e9 que nous pensons susceptible d&#8217;int\u00e9resser les utilisateurs et \u00e0 collecter ou utiliser d&#8217;autres donn\u00e9es sur les activit\u00e9s des utilisateurs sur le site web. Ces soci\u00e9t\u00e9s peuvent diffuser des publicit\u00e9s susceptibles de placer des t\u00e9moins de connexion et de suivre le comportement de l\u2019utilisateur.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p aria-level=\"3\"><span data-contrast=\"auto\">Fonctionnalit\u00e9s des r\u00e9seaux sociaux<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559731&quot;:720,&quot;335559738&quot;:320,&quot;335559739&quot;:80,&quot;335559740&quot;:276,&quot;335559991&quot;:360}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Notre site web peut inclure des fonctionnalit\u00e9s de r\u00e9seaux sociaux, telles que les boutons Facebook et Instagram, les boutons Partage, etc. (collectivement, les \u00ab fonctionnalit\u00e9s de r\u00e9seaux sociaux \u00bb). Ces fonctionnalit\u00e9s de r\u00e9seaux sociaux peuvent collecter votre adresse IP, la page que vous visitez sur notre site web, et peuvent d\u00e9finir un t\u00e9moin de connexion pour permettre aux fonctionnalit\u00e9s de r\u00e9seaux sociaux de fonctionner correctement. Les fonctionnalit\u00e9s des r\u00e9seaux sociaux sont h\u00e9berg\u00e9es soit par leurs fournisseurs respectifs, soit directement sur notre site web. Vos interactions avec ces fonctionnalit\u00e9s de r\u00e9seaux sociaux sont r\u00e9gies par la politique de confidentialit\u00e9 de leurs fournisseurs respectifs.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p aria-level=\"3\"><span data-contrast=\"auto\">Publicit\u00e9 par courriel<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:1440,&quot;335559738&quot;:320,&quot;335559739&quot;:80,&quot;335559740&quot;:276,&quot;335559991&quot;:360}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Nous proposons des infolettres et des campagnes publicitaires \u00e9lectroniques auxquelles vous pouvez vous abonner volontairement \u00e0 tout moment. Nous nous engageons \u00e0 garder votre adresse courriel confidentielle et \u00e0 ne pas la divulguer \u00e0 des tiers, sauf dans la mesure permise dans la <\/span><i><span data-contrast=\"auto\">Section 6: Utilisation des renseignements personnels<\/span><\/i><span data-contrast=\"auto\"> ou dans le but d&#8217;utiliser un fournisseur de service pour envoyer de tels courriels (voir <\/span><i><span data-contrast=\"auto\">Section 9: Communication des renseignements personnels)<\/span><\/i><span data-contrast=\"auto\">. Nous conserverons les informations envoy\u00e9es par courriel conform\u00e9ment aux lois et \u00e0 la r\u00e9glementation applicables.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Conform\u00e9ment \u00e0 la Loi canadienne antipourriel, tous les courriels que nous envoyons indiqueront clairement leur provenance et fourniront des informations claires sur la mani\u00e8re de contacter l&#8217;exp\u00e9diteur. Vous pouvez choisir de ne plus recevoir nos infolettres ou nos courriels publicitaires en suivant les instructions de d\u00e9sabonnement incluses dans ces courriels ou en nous contactant en r\u00e9pondant au courriel. Cependant, vous continuerez \u00e0 recevoir les courriels transactionnels essentiels.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">13. Liens vers d&#8217;autres ressources<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Le site web peut contenir des liens vers d&#8217;autres ressources qui ne nous appartiennent pas ou que nous ne contr\u00f4lons pas. Veuillez noter que nous ne sommes pas responsables des pratiques de confidentialit\u00e9 de ces ressources. Nous vous encourageons \u00e0 \u00eatre conscient lorsque vous quittez notre site web et \u00e0 lire les d\u00e9clarations de confidentialit\u00e9 de chaque ressource susceptible de collecter des informations personnelles.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">14. S\u00e9curit\u00e9 des renseignements fournis<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Nous s\u00e9curisons les informations que vous fournissez sur des serveurs informatiques dans un environnement contr\u00f4l\u00e9 et s\u00e9curis\u00e9, prot\u00e9g\u00e9 contre tout acc\u00e8s, utilisation ou divulgation non autoris\u00e9s. Nous maintenons des mesures de protection administratives, techniques et physiques raisonnables dans le but de nous prot\u00e9ger contre l&#8217;acc\u00e8s, l&#8217;utilisation, la modification et la divulgation non autoris\u00e9s des renseignements personnels sous notre contr\u00f4le et notre garde. Cependant, aucune transmission de donn\u00e9es via Internet ou un r\u00e9seau sans fil ne peut \u00eatre garantie.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Par cons\u00e9quent, alors que nous nous effor\u00e7ons de prot\u00e9ger vos renseignements personnels, vous reconnaissez que :<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><ul><li data-leveltext=\"%1)\" data-font=\"lexend\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:0,&quot;335559684&quot;:-1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[65533,4],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;%1)&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Il existe des limites de s\u00e9curit\u00e9 et de confidentialit\u00e9 d&#8217;Internet qui \u00e9chappent \u00e0 notre contr\u00f4le ;<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li data-leveltext=\"%1)\" data-font=\"lexend\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:0,&quot;335559684&quot;:-1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[65533,4],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;%1)&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">La s\u00e9curit\u00e9, l&#8217;int\u00e9grit\u00e9 et la confidentialit\u00e9 de toutes les informations et donn\u00e9es \u00e9chang\u00e9es entre vous et le site Web et les services ne peuvent \u00eatre garanties ; et<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"> <br \/><\/span><\/li><li data-leveltext=\"%1)\" data-font=\"lexend\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:0,&quot;335559684&quot;:-1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[65533,4],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;%1)&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Ces informations et donn\u00e9es peuvent \u00eatre consult\u00e9es ou alt\u00e9r\u00e9es en transit par un tiers, malgr\u00e9 tous les efforts.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">\u00c9tant donn\u00e9 que la s\u00e9curit\u00e9 des renseignements personnels d\u00e9pend en partie de la s\u00e9curit\u00e9 de l&#8217;appareil que vous utilisez pour communiquer avec nous et des m\u00e9thodes que vous utilisez pour prot\u00e9ger vos informations d&#8217;identification, veuillez prendre les mesures appropri\u00e9es pour prot\u00e9ger ces informations.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">15. Incident de confidentialit\u00e9<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Si nous apprenons que la s\u00e9curit\u00e9 du site web a \u00e9t\u00e9 compromise ou que les renseignements personnels des utilisateurs ont \u00e9t\u00e9 divulgu\u00e9es \u00e0 des tiers non autoris\u00e9s \u00e0 la suite d&#8217;une activit\u00e9 externe, y compris, mais sans s&#8217;y limiter, des attaques de s\u00e9curit\u00e9 ou des fraudes, nous nous r\u00e9servons le droit de prendre des mesures raisonnablement appropri\u00e9es, y compris, mais sans s&#8217;y limiter, des enqu\u00eates et des rapports, ainsi que la notification et la coop\u00e9ration avec les autorit\u00e9s charg\u00e9es de l&#8217;application de la loi.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">En cas d&#8217;incident de confidentialit\u00e9, nous ferons des efforts raisonnables pour informer les personnes concern\u00e9es si nous pensons qu&#8217;il existe un risque raisonnable de pr\u00e9judice \u00e0 la suite de l&#8217;incident ou si un avis est autrement requis par la loi. Si requis, nous publierons un avis sur le site web et nous enverrons un courriel. En cas d&#8217;incident impliquant des renseignements personnels pouvant causer un pr\u00e9judice s\u00e9rieux, nous nous engageons \u00e0 aviser la Commission d&#8217;acc\u00e8s \u00e0 l&#8217;information tel que requis par la loi.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">De plus, nous nous engageons \u00e0 tenir un registre des incidents de confidentialit\u00e9 qui pourrait \u00eatre communiqu\u00e9 sur demande \u00e0 la Commission d&#8217;acc\u00e8s \u00e0 l&#8217;information.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">16. Modification \u00e0 la politique<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Nous nous r\u00e9servons le droit de modifier cette Politique \u00e0 tout moment, \u00e0 notre discr\u00e9tion. Lorsque nous le ferons, nous modifierons la date de mise \u00e0 jour au bas de cette page. Nous pouvons \u00e9galement vous informer des changements apport\u00e9s \u00e0 la Politique par courriel.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">La version mise \u00e0 jour de cette politique entrera en vigueur imm\u00e9diatement apr\u00e8s la publication de la politique r\u00e9vis\u00e9e, sauf indication contraire. Votre utilisation continue du site web et des produits et services offerts par\u00a0 O-Possum apr\u00e8s la date d&#8217;entr\u00e9e en vigueur de la politique r\u00e9vis\u00e9e constitue un consentement implicite \u00e0 ces modifications.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Cependant, nous n&#8217;utilisons pas, sans votre consentement, vos renseignements personnels d&#8217;une mani\u00e8re substantiellement diff\u00e9rente de ce qui a \u00e9t\u00e9 indiqu\u00e9 au moment o\u00f9 vos renseignements personnels ont \u00e9t\u00e9 collect\u00e9s.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">17. Responsables de la protection des renseignements personnels<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Le Responsable des renseignements personnels de\u00a0 O-Possum s&#8217;occupe de la gestion de toutes les donn\u00e9es recueillies.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-contrast=\"auto\">Si vous avez des questions, des pr\u00e9occupations ou des plaintes concernant cette politique, les renseignements que nous d\u00e9tenons \u00e0 votre sujet, ou si vous souhaitez exercer vos droits, nous vous encourageons \u00e0 nous contacter en utilisant les d\u00e9tails ci-dessous : <\/span><span data-contrast=\"auto\">info@o-possum.com<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">18. Acceptation de la pr\u00e9sente politique<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:360,&quot;335559739&quot;:120,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Vous reconnaissez avoir lu cette politique et vous acceptez tous ses termes et conditions. En acc\u00e9dant au site web, en utilisant les produits et services offerts par O-Possum ou en soumettant volontairement vos renseignements personnels, vous acceptez d&#8217;\u00eatre li\u00e9 par cette Politique. Si vous refusez d&#8217;\u00eatre li\u00e9 par la Politique, veuillez ne pas acc\u00e9der au site web, ne pas utiliser nos produits et services et ne pas nous fournir de renseignements personnels.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Ce document a \u00e9t\u00e9 mis \u00e0 jour pour la derni\u00e8re fois le 1er novembre 2023<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique de confidentialit\u00e9 Introduction\u00a0 \u00a0Le respect de votre confidentialit\u00e9 est un enjeu au c\u0153ur des pr\u00e9occupations de l&#8217;\u00e9quipe O-Possum. Nous [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-6981","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 - Vertige escalade<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecom.o-possum.com\/vertige-escalade\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 - Vertige escalade\" \/>\n<meta property=\"og:description\" content=\"Politique de confidentialit\u00e9 Introduction\u00a0 \u00a0Le respect de votre confidentialit\u00e9 est un enjeu au c\u0153ur des pr\u00e9occupations de l&#8217;\u00e9quipe O-Possum. Nous [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecom.o-possum.com\/vertige-escalade\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Vertige escalade\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-31T17:20:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecom.o-possum.com\\\/vertige-escalade\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/ecom.o-possum.com\\\/vertige-escalade\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 - Vertige escalade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecom.o-possum.com\\\/vertige-escalade\\\/#website\"},\"datePublished\":\"2020-08-26T22:31:31+00:00\",\"dateModified\":\"2023-10-31T17:20:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecom.o-possum.com\\\/vertige-escalade\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecom.o-possum.com\\\/vertige-escalade\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecom.o-possum.com\\\/vertige-escalade\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecom.o-possum.com\\\/vertige-escalade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecom.o-possum.com\\\/vertige-escalade\\\/#website\",\"url\":\"https:\\\/\\\/ecom.o-possum.com\\\/vertige-escalade\\\/\",\"name\":\"Vertige escalade\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecom.o-possum.com\\\/vertige-escalade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 - Vertige escalade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecom.o-possum.com\/vertige-escalade\/politique-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 - Vertige escalade","og_description":"Politique de confidentialit\u00e9 Introduction\u00a0 \u00a0Le respect de votre confidentialit\u00e9 est un enjeu au c\u0153ur des pr\u00e9occupations de l&#8217;\u00e9quipe O-Possum. Nous [&hellip;]","og_url":"https:\/\/ecom.o-possum.com\/vertige-escalade\/politique-de-confidentialite\/","og_site_name":"Vertige escalade","article_modified_time":"2023-10-31T17:20:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecom.o-possum.com\/vertige-escalade\/politique-de-confidentialite\/","url":"https:\/\/ecom.o-possum.com\/vertige-escalade\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 - Vertige escalade","isPartOf":{"@id":"https:\/\/ecom.o-possum.com\/vertige-escalade\/#website"},"datePublished":"2020-08-26T22:31:31+00:00","dateModified":"2023-10-31T17:20:06+00:00","breadcrumb":{"@id":"https:\/\/ecom.o-possum.com\/vertige-escalade\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecom.o-possum.com\/vertige-escalade\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ecom.o-possum.com\/vertige-escalade\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecom.o-possum.com\/vertige-escalade\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/ecom.o-possum.com\/vertige-escalade\/#website","url":"https:\/\/ecom.o-possum.com\/vertige-escalade\/","name":"Vertige escalade","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecom.o-possum.com\/vertige-escalade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/ecom.o-possum.com\/vertige-escalade\/wp-json\/wp\/v2\/pages\/6981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecom.o-possum.com\/vertige-escalade\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecom.o-possum.com\/vertige-escalade\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecom.o-possum.com\/vertige-escalade\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecom.o-possum.com\/vertige-escalade\/wp-json\/wp\/v2\/comments?post=6981"}],"version-history":[{"count":0,"href":"https:\/\/ecom.o-possum.com\/vertige-escalade\/wp-json\/wp\/v2\/pages\/6981\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecom.o-possum.com\/vertige-escalade\/wp-json\/wp\/v2\/media?parent=6981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}